{"id":27712,"date":"2023-05-24T12:17:31","date_gmt":"2023-05-24T16:17:31","guid":{"rendered":"https:\/\/survivornet.ca\/?p=27712"},"modified":"2023-06-12T12:15:29","modified_gmt":"2023-06-12T16:15:29","slug":"connaissez-vous-bien-le-soleil","status":"publish","type":"post","link":"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/","title":{"rendered":"Connaissez-vous bien le Soleil\u00a0?"},"content":{"rendered":"<p>Quand, pour la premi\u00e8re fois, j&#8217;ai vu qu&#8217;il y avait un mois de sensibilisation au soleil, j&#8217;ai trouv\u00e9 que c&#8217;\u00e9tait un peu ridicule.<\/p>\n<p>Bien s\u00fbr, les gens sont conscients des effets du soleil. C&#8217;est un rappel constant qu&#8217;une trop grande exposition peut \u00eatre une mauvaise chose, d&#8217;un simple coup de soleil \u00e0 un risque accru de m\u00e9lanome. Depuis l&#8217;enfance, il est clair que lorsque vous sortez, vous devez soit vous badigeonner de cette cr\u00e8me \u00e0 l&#8217;odeur \u00e9trange, soit vous couvrir de la t\u00eate aux pieds. La seule autre option est d&#8217;\u00e9viter compl\u00e8tement le soleil. Alors oui, les canadiens sont tr\u00e8s conscients des effets du soleil.<\/p>\n<p>Cependant, les taux de cancer de la peau au Canada augmentent. Alors, quelle est la v\u00e9ritable prise de conscience autour du soleil ?<\/p>\n<p>Le m\u00e9lanome repr\u00e9sente actuellement environ 5,5 % du nombre total de diagnostics de cancer au Canada, le quatri\u00e8me apr\u00e8s le cancer du sein, de la prostate et du colon. La Soci\u00e9t\u00e9 Canadienne du Cancer affirme que le diagnostic de m\u00e9lanome continue d&#8217;augmenter, bien que la maladie soit la plus \u00e9vitable de tous les cancers. La Canadian Skin Cancer Foundation (CSCF) sonne encore plus l&#8217;alarme, affirmant que nous retrouvons chaque ann\u00e9e plus de nouveaux cas de cancer de la peau que de cancers du sein, de la prostate, du poumon et du c\u00f4lon r\u00e9unis. De plus, ils affirment que les personnes n\u00e9es dans les ann\u00e9es 1990 ont un risque deux \u00e0 trois fois plus \u00e9lev\u00e9 de d\u00e9velopper un cancer de la peau que celles n\u00e9es dans les ann\u00e9es 1960.<\/p>\n<p>Les raisons de cette affirmation sont toujours \u00e0 l&#8217;\u00e9tude, mais nous pouvons d\u00e9j\u00e0 pointer du doigt quelques coupables majeurs.<\/p>\n<p>L&#8217;exposition \u00e0 la lumi\u00e8re ultraviolette, ou lumi\u00e8re UV, est la force motrice de la plupart des cancers de la peau, et elle est r\u00e9pertori\u00e9e comme canc\u00e9rog\u00e8ne du groupe 1 du Centre International de Recherche sur le Cancer (CIRC). L&#8217;utilisation des lits de bronzage a \u00e9t\u00e9 li\u00e9e \u00e0 l&#8217;augmentation des m\u00e9lanomes, car ils \u00e9mettent parfois des rayons UV jusqu&#8217;\u00e0 15 fois plus \u00e9lev\u00e9s que le soleil \u00e0 son intensit\u00e9 maximale. Le groupe de travail du CIRC affirme que l&#8217;utilisation d&#8217;un lit de bronzage avant l&#8217;\u00e2ge de 35 ans augmente le risque de m\u00e9lanome de 75 %.<\/p>\n<p>Cette tendance touche malheureusement plus les femmes que les hommes. L&#8217;American Academy of Dermatology Association a publi\u00e9 un article indiquant que le cancer de la peau a augment\u00e9 de 800 % chez les femmes \u00e2g\u00e9es de 18 \u00e0 39 ans entre 1970 et 2009. L&#8217;utilisation accrue des lits de bronzage, qui sont utilis\u00e9s par les femmes \u00e0 un taux beaucoup plus \u00e9lev\u00e9 que les hommes, a \u00e9t\u00e9 directement bl\u00e2m\u00e9 pour cette augmentation. Apr\u00e8s un coup d&#8217;\u0153il rapide sur le bronzage et son r\u00f4le dans les normes de beaut\u00e9 aujourd&#8217;hui, on comprend pourquoi des cancers comme celui-ci restent r\u00e9pandus chez les jeunes femmes.<\/p>\n<p>La deuxi\u00e8me raison de l&#8217;augmentation des taux de m\u00e9lanome est l&#8217;appauvrissement de la couche d&#8217;ozone. Il est bien connu que des \u00ab trous \u00bb dans la couche d&#8217;ozone ont \u00e9t\u00e9 d\u00e9tect\u00e9s depuis la fin des ann\u00e9es 1970, souvent en raison de l&#8217;utilisation de produits chimiques comme les chlorofluorocarbures (CFC) et les hydrochlorofluorocarbures (HCFC). Il existe des preuves que ces trous pr\u00e9sents dans des zones o\u00f9 la couche d&#8217;ozone est extr\u00eamement mince se r\u00e9tr\u00e9cissent. On soup\u00e7onnait qu&#8217;au milieu des ann\u00e9es 1990, la d\u00e9gradation de la couche avait atteint son apog\u00e9e. Cependant, les scientifiques pensent que nous ne saurons pas avec certitude si nos efforts pour r\u00e9parer la couche d&#8217;ozone ont port\u00e9 leurs fruits avant 2030.<\/p>\n<p>La couche d&#8217;ozone prot\u00e8ge la terre des rayons UV nocifs, et une couche d&#8217;ozone r\u00e9duite a \u00e9t\u00e9 associ\u00e9e au cancer de la peau. Environnement Canada pr\u00e9voit que la couche est \u00e0 son plus mince vers la fin de l&#8217;hiver et au d\u00e9but du printemps et qu&#8217;elle \u00e9tait \u00e0 son plus bas niveau dans les ann\u00e9es 1990. C&#8217;est pourquoi il est important d&#8217;utiliser un \u00e9cran solaire m\u00eame pendant les mois les plus froids de l&#8217;ann\u00e9e.<\/p>\n<p>Il est vrai que dire aux gens de faire attention au soleil semble ridicule car cela touche presque tout dans notre vie, mais tout comme certains jeunes pensent que vapoter est plus s\u00fbr que fumer, comprendre ce qu&#8217;est le soleil et ses effets peut nous emp\u00eacher de subir ses c\u00f4t\u00e9s les plus nocifs. Ce n&#8217;est pas parce que le soleil est l\u00e0 que vous savez ce qu&#8217;il implique ou comment il est li\u00e9 au cancer.<\/p>\n<p>Consultez notre page sur les faits et les mythes du m\u00e9lanome <a href=\"https:\/\/survivornet.ca\/cancer-type\/skin-cancer-melanoma\/melanoma-myths-facts\/\"><strong>ici<\/strong><\/a> (en anglais). Pour v\u00e9rifier si vous \u00eates atteint d&#8217;un cancer de la peau, consultez la proc\u00e9dure d&#8217;examen de l&#8217;Association Canadienne de Dermatologie <a href=\"https:\/\/dermatologue.ca\/patients-et-grand-public\/prudence-au-soleil\/mois-de-prudence-au-soleil\/\"><strong>ici<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand, pour la premi\u00e8re fois, j&#8217;ai vu qu&#8217;il y avait un mois de sensibilisation au soleil, j&#8217;ai trouv\u00e9 que c&#8217;\u00e9tait un peu ridicule. Bien s\u00fbr, les gens sont conscients des effets du<\/p>\n","protected":false},"author":2,"featured_media":27705,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-27712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Connaissez-vous bien le Soleil\u00a0? - Canadian Cancer Survivor Network<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Connaissez-vous bien le Soleil\u00a0? - Canadian Cancer Survivor Network\" \/>\n<meta property=\"og:description\" content=\"Quand, pour la premi\u00e8re fois, j&#8217;ai vu qu&#8217;il y avait un mois de sensibilisation au soleil, j&#8217;ai trouv\u00e9 que c&#8217;\u00e9tait un peu ridicule. Bien s\u00fbr, les gens sont conscients des effets du\" \/>\n<meta property=\"og:url\" content=\"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/\" \/>\n<meta property=\"og:site_name\" content=\"Canadian Cancer Survivor Network\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-24T16:17:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-12T16:15:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/survivornet.ca\/wp-content\/uploads\/2023\/05\/sun-g627835d7a_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Canadian Cancer Survivor Network\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canadian Cancer Survivor Network\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/survivornet.ca\\\/fr\\\/connaissez-vous-bien-le-soleil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/survivornet.ca\\\/fr\\\/connaissez-vous-bien-le-soleil\\\/\"},\"author\":{\"name\":\"Canadian Cancer Survivor Network\",\"@id\":\"https:\\\/\\\/survivornet.ca\\\/#\\\/schema\\\/person\\\/cd88dd5422122126efae4939af08c8a3\"},\"headline\":\"Connaissez-vous bien le Soleil\u00a0?\",\"datePublished\":\"2023-05-24T16:17:31+00:00\",\"dateModified\":\"2023-06-12T16:15:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/survivornet.ca\\\/fr\\\/connaissez-vous-bien-le-soleil\\\/\"},\"wordCount\":853,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/survivornet.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/survivornet.ca\\\/fr\\\/connaissez-vous-bien-le-soleil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/survivornet.ca\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/sun-g627835d7a_1920.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/survivornet.ca\\\/fr\\\/connaissez-vous-bien-le-soleil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/survivornet.ca\\\/fr\\\/connaissez-vous-bien-le-soleil\\\/\",\"url\":\"https:\\\/\\\/survivornet.ca\\\/fr\\\/connaissez-vous-bien-le-soleil\\\/\",\"name\":\"Connaissez-vous bien le Soleil\u00a0? - Canadian Cancer Survivor Network\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/survivornet.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/survivornet.ca\\\/fr\\\/connaissez-vous-bien-le-soleil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/survivornet.ca\\\/fr\\\/connaissez-vous-bien-le-soleil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/survivornet.ca\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/sun-g627835d7a_1920.jpg\",\"datePublished\":\"2023-05-24T16:17:31+00:00\",\"dateModified\":\"2023-06-12T16:15:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/survivornet.ca\\\/fr\\\/connaissez-vous-bien-le-soleil\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/survivornet.ca\\\/fr\\\/connaissez-vous-bien-le-soleil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/survivornet.ca\\\/fr\\\/connaissez-vous-bien-le-soleil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/survivornet.ca\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/sun-g627835d7a_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/survivornet.ca\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/sun-g627835d7a_1920.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/survivornet.ca\\\/fr\\\/connaissez-vous-bien-le-soleil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/survivornet.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Connaissez-vous bien le Soleil\u00a0?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/survivornet.ca\\\/#website\",\"url\":\"https:\\\/\\\/survivornet.ca\\\/\",\"name\":\"Canadian Cancer Survivor Network\",\"description\":\"The Canadian Cancer Survivor Network was created by a group of Canadians concerned about cancer.\",\"publisher\":{\"@id\":\"https:\\\/\\\/survivornet.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/survivornet.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/survivornet.ca\\\/#organization\",\"name\":\"Canadian Cancer Survivor Network\",\"url\":\"https:\\\/\\\/survivornet.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/survivornet.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/survivornet.ca\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/CCSN_Logo_EN_SQUARE.png\",\"contentUrl\":\"http:\\\/\\\/survivornet.ca\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/CCSN_Logo_EN_SQUARE.png\",\"width\":1209,\"height\":1007,\"caption\":\"Canadian Cancer Survivor Network\"},\"image\":{\"@id\":\"https:\\\/\\\/survivornet.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/survivornet.ca\\\/#\\\/schema\\\/person\\\/cd88dd5422122126efae4939af08c8a3\",\"name\":\"Canadian Cancer Survivor Network\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33aa360244fcdfbe1c6cf70c3e0ad24e078d2b2d1d0f84de9c64ac1b3ec739a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33aa360244fcdfbe1c6cf70c3e0ad24e078d2b2d1d0f84de9c64ac1b3ec739a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33aa360244fcdfbe1c6cf70c3e0ad24e078d2b2d1d0f84de9c64ac1b3ec739a8?s=96&d=mm&r=g\",\"caption\":\"Canadian Cancer Survivor Network\"},\"url\":\"https:\\\/\\\/survivornet.ca\\\/fr\\\/author\\\/canadian-cancer-suvivor-network\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Connaissez-vous bien le Soleil\u00a0? - Canadian Cancer Survivor Network","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/","og_locale":"fr_FR","og_type":"article","og_title":"Connaissez-vous bien le Soleil\u00a0? - Canadian Cancer Survivor Network","og_description":"Quand, pour la premi\u00e8re fois, j&#8217;ai vu qu&#8217;il y avait un mois de sensibilisation au soleil, j&#8217;ai trouv\u00e9 que c&#8217;\u00e9tait un peu ridicule. Bien s\u00fbr, les gens sont conscients des effets du","og_url":"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/","og_site_name":"Canadian Cancer Survivor Network","article_published_time":"2023-05-24T16:17:31+00:00","article_modified_time":"2023-06-12T16:15:29+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/survivornet.ca\/wp-content\/uploads\/2023\/05\/sun-g627835d7a_1920.jpg","type":"image\/jpeg"}],"author":"Canadian Cancer Survivor Network","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Canadian Cancer Survivor Network","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/#article","isPartOf":{"@id":"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/"},"author":{"name":"Canadian Cancer Survivor Network","@id":"https:\/\/survivornet.ca\/#\/schema\/person\/cd88dd5422122126efae4939af08c8a3"},"headline":"Connaissez-vous bien le Soleil\u00a0?","datePublished":"2023-05-24T16:17:31+00:00","dateModified":"2023-06-12T16:15:29+00:00","mainEntityOfPage":{"@id":"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/"},"wordCount":853,"commentCount":1,"publisher":{"@id":"https:\/\/survivornet.ca\/#organization"},"image":{"@id":"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/#primaryimage"},"thumbnailUrl":"https:\/\/survivornet.ca\/wp-content\/uploads\/2023\/05\/sun-g627835d7a_1920.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/","url":"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/","name":"Connaissez-vous bien le Soleil\u00a0? - Canadian Cancer Survivor Network","isPartOf":{"@id":"https:\/\/survivornet.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/#primaryimage"},"image":{"@id":"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/#primaryimage"},"thumbnailUrl":"https:\/\/survivornet.ca\/wp-content\/uploads\/2023\/05\/sun-g627835d7a_1920.jpg","datePublished":"2023-05-24T16:17:31+00:00","dateModified":"2023-06-12T16:15:29+00:00","breadcrumb":{"@id":"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/#primaryimage","url":"https:\/\/survivornet.ca\/wp-content\/uploads\/2023\/05\/sun-g627835d7a_1920.jpg","contentUrl":"https:\/\/survivornet.ca\/wp-content\/uploads\/2023\/05\/sun-g627835d7a_1920.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/survivornet.ca\/fr\/connaissez-vous-bien-le-soleil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/survivornet.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Connaissez-vous bien le Soleil\u00a0?"}]},{"@type":"WebSite","@id":"https:\/\/survivornet.ca\/#website","url":"https:\/\/survivornet.ca\/","name":"Canadian Cancer Survivor Network","description":"The Canadian Cancer Survivor Network was created by a group of Canadians concerned about cancer.","publisher":{"@id":"https:\/\/survivornet.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/survivornet.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/survivornet.ca\/#organization","name":"Canadian Cancer Survivor Network","url":"https:\/\/survivornet.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/survivornet.ca\/#\/schema\/logo\/image\/","url":"http:\/\/survivornet.ca\/wp-content\/uploads\/2016\/12\/CCSN_Logo_EN_SQUARE.png","contentUrl":"http:\/\/survivornet.ca\/wp-content\/uploads\/2016\/12\/CCSN_Logo_EN_SQUARE.png","width":1209,"height":1007,"caption":"Canadian Cancer Survivor Network"},"image":{"@id":"https:\/\/survivornet.ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/survivornet.ca\/#\/schema\/person\/cd88dd5422122126efae4939af08c8a3","name":"Canadian Cancer Survivor Network","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/33aa360244fcdfbe1c6cf70c3e0ad24e078d2b2d1d0f84de9c64ac1b3ec739a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/33aa360244fcdfbe1c6cf70c3e0ad24e078d2b2d1d0f84de9c64ac1b3ec739a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33aa360244fcdfbe1c6cf70c3e0ad24e078d2b2d1d0f84de9c64ac1b3ec739a8?s=96&d=mm&r=g","caption":"Canadian Cancer Survivor Network"},"url":"https:\/\/survivornet.ca\/fr\/author\/canadian-cancer-suvivor-network\/"}]}},"_links":{"self":[{"href":"https:\/\/survivornet.ca\/fr\/wp-json\/wp\/v2\/posts\/27712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/survivornet.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/survivornet.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/survivornet.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/survivornet.ca\/fr\/wp-json\/wp\/v2\/comments?post=27712"}],"version-history":[{"count":2,"href":"https:\/\/survivornet.ca\/fr\/wp-json\/wp\/v2\/posts\/27712\/revisions"}],"predecessor-version":[{"id":27767,"href":"https:\/\/survivornet.ca\/fr\/wp-json\/wp\/v2\/posts\/27712\/revisions\/27767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/survivornet.ca\/fr\/wp-json\/wp\/v2\/media\/27705"}],"wp:attachment":[{"href":"https:\/\/survivornet.ca\/fr\/wp-json\/wp\/v2\/media?parent=27712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/survivornet.ca\/fr\/wp-json\/wp\/v2\/categories?post=27712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/survivornet.ca\/fr\/wp-json\/wp\/v2\/tags?post=27712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}